{"id":48353,"date":"2026-03-04T08:20:16","date_gmt":"2026-03-04T07:20:16","guid":{"rendered":"https:\/\/rrgsuisse.ch\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026"},"modified":"2026-04-14T11:23:38","modified_gmt":"2026-04-14T09:23:38","slug":"renault-dacia-und-alpine-an-der-autoxperience-geneve-2026","status":"publish","type":"post","link":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026","title":{"rendered":"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026"},"content":{"rendered":"<div class=\"description\">\n\t\t\t\t\t\t\t\t\tUrdorf, 3. M\u00e4rz 2026 \u2013 Die Retail Renault Group (RRG) Schweiz ist mit Renault, Dacia und Alpine bei der AutoXp\u00e9rience Gen\u00e8ve 2026 in der Palexpo Genf vertreten. Auf einer Gesamtfl\u00e4che von 932 m\u00b2 zeigt die RRG insgesamt 19 Fahrzeuge und bietet Besucherinnen und Besuchern die M\u00f6glichkeit, zahlreiche Modelle direkt vor Ort Probe zu fahren. Am Donnerstag, dem exklusiven Er\u00f6ffnungsabend, k\u00f6nnen geladene Besucher*innen die Ausstellung im Rahmen der \u00abRRG Poptimes Night\u00bb ab 20:00 Uhr mit Animationen, einem reichhaltigen Ap\u00e9ro riche in festlicher Atmosph\u00e4re erkunden, und im Originals-Shop in Ruhe einkaufen.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.renault.ch\/__\/157055.d75f6cc2.jpg\" alt=\"\" \/><\/figure>\n<p>\nDie Besucherinnen und Besucher erwartet ein umfassender \u00dcberblick \u00fcber die aktuellen Modellpaletten der drei Marken. Die Bandbreite erstreckt sich von rein elektrischen Kleinwagen bis hin zu grossen full hybrid SUVs und unterstreicht den Anspruch der RRG, f\u00fcr jedes Mobilit\u00e4tsbed\u00fcrfnis das optimale Fahrzeug anzubieten.<\/p>\n<p><b>Bruno Veyssade, Generaldirektor von RRG Schweiz<\/b>: <i>\u00abDie AutoXp\u00e9rience bietet uns eine ideale Plattform, um das Angebot aller unserer Marken erlebbar zu machen. Wir freuen uns, den Besucherinnen und Besuchern mit unserer vielf\u00e4ltigen Palette an Modellen und Antrieben die passende Mobilit\u00e4tsl\u00f6sung f\u00fcr ihre individuellen Bed\u00fcrfnisse anbieten zu k\u00f6nnen. Die M\u00f6glichkeit, viele Fahrzeuge direkt vor Ort Probe zu fahren, unterstreicht den kundenorientierten Charakter dieser Messe.\u00bb<\/i><\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.renault.ch\/__\/150466.bcd2928e.jpg\" alt=\"\" \/><\/figure>\n<p>\n<b>Neuheiten und Highlights von Renault auf dem RRG-Stand<\/b>:<\/p>\n<ul class=\"list\">\n<li>Renault 5 E-Tech electric<\/li>\n<li>Renault Scenic E-Tech electric<\/li>\n<li>Renault Symbioz<\/li>\n<li>Neuer Renault Clio<\/li>\n<li>Renault Captur<\/li>\n<li>Renault 4 E-Tech electric<\/li>\n<li>Renault Austral<\/li>\n<li>Renault Espace<\/li>\n<li>Renault Rafale<\/li>\n<li>Renault Megane E-Tech electric<\/li>\n<li>Renault Kangoo E-Tech electric<\/li>\n<\/ul>\n<p>\n<b>Neuheiten und Highlights von Dacia auf dem RRG-Stand<\/b>:<\/p>\n<ul class=\"list\">\n<li>Dacia Duster<\/li>\n<li>Dacia Bigster<\/li>\n<li>Dacia Jogger<\/li>\n<li>Dacia Spring electric<\/li>\n<li>Dacia Sandero<\/li>\n<\/ul>\n<p>\n<b>Neuheiten und Highlights von Alpine auf dem RRG-Stand<\/b>:<\/p>\n<ul class=\"list\">\n<li>Alpine A110<\/li>\n<li>Alpine A290<\/li>\n<li>Alpine A390<\/li>\n<\/ul>\n<p>\n<b>Testfahrzeuge in der Test-Drive-Zone<\/b>:<\/p>\n<ul class=\"list\">\n<li>Renault 5 E-Tech electric<\/li>\n<li>Renault Scenic E-Tech electric<\/li>\n<li>Neuer Renault Clio<\/li>\n<li>Renault 4 E-Tech electric<\/li>\n<li>Renault Rafale<\/li>\n<li>Renault Austral<\/li>\n<li>Dacia Bigster<\/li>\n<li>Dacia Duster<\/li>\n<li>Alpine A290<\/li>\n<li>Alpine A390<\/li>\n<\/ul>\n<p>\n<b>\u00d6ffnungszeiten<\/b>:<\/p>\n<ul class=\"list\">\n<li>Freitag, 6. M\u00e4rz: 10:00 \u2013 20:00 Uhr<\/li>\n<li>Samstag, 7. M\u00e4rz: 10:00 \u2013 20:00 Uhr<\/li>\n<li>Sonntag, 8. M\u00e4rz: 10:00 \u2013 18:00 Uhr<\/li>\n<\/ul>\n<p>\n<b>Ticketpreise<\/b>:<\/p>\n<ul class=\"list\">\n<li>Erwachsene: CHF 10.- (vor Ort CHF 13.-)<\/li>\n<li>Studenten, IV, AHV-Senioren, Kinder bis 16 Jahre: CHF 0.- (vor Ort CHF 5.-)<\/li>\n<\/ul>\n<p>\n<b>Link zur Messe-Website<\/b>: <a target=\"_blank\" href=\"https:\/\/www.autoxperience.ch\/\">https:\/\/www.autoxperience.ch\/<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Retail Renault Group (RRG) Schweiz pr\u00e4sentiert aktuelle Modelle von Renault, Dacia und Alpine bei der AutoXp\u00e9rience Gen\u00e8ve 2026 in der Palexpo Genf932 m\u00b2 Standfl\u00e4che mit 19 Fahrzeugen aller MarkenZehn Fahrzeuge stehen in der Test-Drive-Zone f\u00fcr Probefahrten zur Verf\u00fcgungVIP-Er\u00f6ffnungsevent \u00abRRG POPTIMES\u00bb am Donnerstagabend<\/p>\n","protected":false},"author":1,"featured_media":48354,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[37,126,130,127],"tags":[],"class_list":["post-48353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une-de","category-actualite-alpine-de","category-actualite-dacia-de","category-actualite-renault-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026 - RRG Suisse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026 - RRG Suisse\" \/>\n<meta property=\"og:description\" content=\"Die Retail Renault Group (RRG) Schweiz pr\u00e4sentiert aktuelle Modelle von Renault, Dacia und Alpine bei der AutoXp\u00e9rience Gen\u00e8ve 2026 in der Palexpo Genf932 m\u00b2 Standfl\u00e4che mit 19 Fahrzeugen aller MarkenZehn Fahrzeuge stehen in der Test-Drive-Zone f\u00fcr Probefahrten zur Verf\u00fcgungVIP-Er\u00f6ffnungsevent \u00abRRG POPTIMES\u00bb am Donnerstagabend\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026\" \/>\n<meta property=\"og:site_name\" content=\"RRG Suisse\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-04T07:20:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T09:23:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rrgsuisse.ch\/wp-content\/uploads\/2026\/03\/163008.30bb6cd2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rrgsuisse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rrgsuisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026\"},\"author\":{\"name\":\"rrgsuisse\",\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de#\\\/schema\\\/person\\\/3fb0fceb9f1a5bcb4c674661a09ea4f7\"},\"headline\":\"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026\",\"datePublished\":\"2026-03-04T07:20:16+00:00\",\"dateModified\":\"2026-04-14T09:23:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026\"},\"wordCount\":360,\"image\":{\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rrgsuisse.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/163008.30bb6cd2-1.jpg\",\"articleSection\":[\"A la une\",\"Actualit\u00e9 Alpine\",\"Actualit\u00e9 Dacia\",\"Actualit\u00e9 Renault\"],\"inLanguage\":\"de-CH\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026\",\"url\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026\",\"name\":\"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026 - RRG Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rrgsuisse.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/163008.30bb6cd2-1.jpg\",\"datePublished\":\"2026-03-04T07:20:16+00:00\",\"dateModified\":\"2026-04-14T09:23:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de#\\\/schema\\\/person\\\/3fb0fceb9f1a5bcb4c674661a09ea4f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#primaryimage\",\"url\":\"https:\\\/\\\/rrgsuisse.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/163008.30bb6cd2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/rrgsuisse.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/163008.30bb6cd2-1.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de#website\",\"url\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\",\"name\":\"RRG Suisse\",\"description\":\"Retail Renault Group - Revendeur officiel Renault, Dacia, Nissan\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rrgsuisse.ch\\\/de?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rrgsuisse.ch\\\/de#\\\/schema\\\/person\\\/3fb0fceb9f1a5bcb4c674661a09ea4f7\",\"name\":\"rrgsuisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e8e0f3f10010a38feb43e707770c4c97735143a26d51396eb4f3ea6bb49ed57?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e8e0f3f10010a38feb43e707770c4c97735143a26d51396eb4f3ea6bb49ed57?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e8e0f3f10010a38feb43e707770c4c97735143a26d51396eb4f3ea6bb49ed57?s=96&d=mm&r=g\",\"caption\":\"rrgsuisse\"},\"sameAs\":[\"https:\\\/\\\/rrgsuisse.ch\"],\"url\":\"https:\\\/\\\/rrgsuisse.ch\\\/de\\\/author\\\/rrgsuisse\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026 - RRG Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026","og_locale":"de_DE","og_type":"article","og_title":"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026 - RRG Suisse","og_description":"Die Retail Renault Group (RRG) Schweiz pr\u00e4sentiert aktuelle Modelle von Renault, Dacia und Alpine bei der AutoXp\u00e9rience Gen\u00e8ve 2026 in der Palexpo Genf932 m\u00b2 Standfl\u00e4che mit 19 Fahrzeugen aller MarkenZehn Fahrzeuge stehen in der Test-Drive-Zone f\u00fcr Probefahrten zur Verf\u00fcgungVIP-Er\u00f6ffnungsevent \u00abRRG POPTIMES\u00bb am Donnerstagabend","og_url":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026","og_site_name":"RRG Suisse","article_published_time":"2026-03-04T07:20:16+00:00","article_modified_time":"2026-04-14T09:23:38+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/rrgsuisse.ch\/wp-content\/uploads\/2026\/03\/163008.30bb6cd2-1.jpg","type":"image\/jpeg"}],"author":"rrgsuisse","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"rrgsuisse","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#article","isPartOf":{"@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026"},"author":{"name":"rrgsuisse","@id":"https:\/\/rrgsuisse.ch\/de#\/schema\/person\/3fb0fceb9f1a5bcb4c674661a09ea4f7"},"headline":"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026","datePublished":"2026-03-04T07:20:16+00:00","dateModified":"2026-04-14T09:23:38+00:00","mainEntityOfPage":{"@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026"},"wordCount":360,"image":{"@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#primaryimage"},"thumbnailUrl":"https:\/\/rrgsuisse.ch\/wp-content\/uploads\/2026\/03\/163008.30bb6cd2-1.jpg","articleSection":["A la une","Actualit\u00e9 Alpine","Actualit\u00e9 Dacia","Actualit\u00e9 Renault"],"inLanguage":"de-CH"},{"@type":"WebPage","@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026","url":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026","name":"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026 - RRG Suisse","isPartOf":{"@id":"https:\/\/rrgsuisse.ch\/de#website"},"primaryImageOfPage":{"@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#primaryimage"},"image":{"@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#primaryimage"},"thumbnailUrl":"https:\/\/rrgsuisse.ch\/wp-content\/uploads\/2026\/03\/163008.30bb6cd2-1.jpg","datePublished":"2026-03-04T07:20:16+00:00","dateModified":"2026-04-14T09:23:38+00:00","author":{"@id":"https:\/\/rrgsuisse.ch\/de#\/schema\/person\/3fb0fceb9f1a5bcb4c674661a09ea4f7"},"breadcrumb":{"@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#primaryimage","url":"https:\/\/rrgsuisse.ch\/wp-content\/uploads\/2026\/03\/163008.30bb6cd2-1.jpg","contentUrl":"https:\/\/rrgsuisse.ch\/wp-content\/uploads\/2026\/03\/163008.30bb6cd2-1.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/rrgsuisse.ch\/de\/renault-dacia-und-alpine-an-der-autoxperience-geneve-2026#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rrgsuisse.ch\/de"},{"@type":"ListItem","position":2,"name":"Renault, Dacia und Alpine an der AutoXp\u00e9rience Gen\u00e8ve 2026"}]},{"@type":"WebSite","@id":"https:\/\/rrgsuisse.ch\/de#website","url":"https:\/\/rrgsuisse.ch\/de","name":"RRG Suisse","description":"Retail Renault Group - Revendeur officiel Renault, Dacia, Nissan","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rrgsuisse.ch\/de?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/rrgsuisse.ch\/de#\/schema\/person\/3fb0fceb9f1a5bcb4c674661a09ea4f7","name":"rrgsuisse","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/5e8e0f3f10010a38feb43e707770c4c97735143a26d51396eb4f3ea6bb49ed57?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e8e0f3f10010a38feb43e707770c4c97735143a26d51396eb4f3ea6bb49ed57?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e8e0f3f10010a38feb43e707770c4c97735143a26d51396eb4f3ea6bb49ed57?s=96&d=mm&r=g","caption":"rrgsuisse"},"sameAs":["https:\/\/rrgsuisse.ch"],"url":"https:\/\/rrgsuisse.ch\/de\/author\/rrgsuisse"}]}},"wpml_current_locale":"de_CH","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/posts\/48353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/comments?post=48353"}],"version-history":[{"count":1,"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/posts\/48353\/revisions"}],"predecessor-version":[{"id":48356,"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/posts\/48353\/revisions\/48356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/media\/48354"}],"wp:attachment":[{"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/media?parent=48353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/categories?post=48353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rrgsuisse.ch\/de\/wp-json\/wp\/v2\/tags?post=48353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}